{"id":429,"date":"2023-05-30T10:58:40","date_gmt":"2023-05-30T10:58:40","guid":{"rendered":"https:\/\/groseko.webclientes.es\/contacto\/"},"modified":"2024-09-23T10:47:52","modified_gmt":"2024-09-23T10:47:52","slug":"contact","status":"publish","type":"page","link":"https:\/\/grosekoindarra.webclientes.es\/fr\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Secci\u00f3n&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Contactez-nous<\/h1>\n<p>[\/et_pb_text][dvppl_cf7_styler cf7=&#8221;1537&#8243; form_field_height=&#8221;50px&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dvppl_cf7_styler][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Heures de Bureau<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]- Mardi eta jeudi de 13:30 \u00e0 18:30.<br \/>\n&#8211; Mercredi de 10:00 \u00e0 15:00.[\/et_pb_text][et_pb_code _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d2902.3775993813124!2d-1.9715059999999998!3d43.327287!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd51a5417b173123%3A0x6a762fcd16c9531f!2sGroseko%20Indarra%20Surf%20Eskola-Taldea!5e0!3m2!1ses!2sus!4v1685526816804!5m2!1ses!2sus\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contactez-nous<div class=\"et_pb_module dvppl_cf7_styler dvppl_cf7_styler_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dipe-cf7-container dipe-cf7-button-left\">\n\t\t\t\t\n\t\t\t\t<div class=\"dipe-cf7 dipe-cf7-styler \">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1537-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/429#wpcf7-f1537-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1537\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1537-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"NOMBRE\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu nombre (obligatorio)\" value=\"\" type=\"text\" name=\"NOMBRE\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"CORREO\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu email (obligatorio)\" value=\"\" type=\"email\" name=\"CORREO\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"TELEFONO\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Tu numero de contacto\" value=\"\" type=\"tel\" name=\"TELEFONO\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"MENSAJE\"><textarea cols=\"40\" rows=\"5\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Tu mensaje\" name=\"MENSAJE\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"RGPD\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"RGPD\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>He le\u00eddo y acepto la <a href=\"\/es\/politica-privacidad\/\" target=\"_blank\">pol\u00edtica de privacidad<\/a>.\n<\/p>\n<p><button class=\"wpcf7-form-control wpcf7-submit has-spinner et_pb_button et_pb_bg_layout_light\" type=\"submit\" value=\"Enviar\">Enviar<\/button>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Heures de Bureau- Mardi eta jeudi de 13:30 \u00e0 18:30. &#8211; Mercredi de 10:00 \u00e0 15:00.<\/p>\n","protected":false},"author":2,"featured_media":812,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/pages\/429"}],"collection":[{"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":7,"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/pages\/429\/revisions"}],"predecessor-version":[{"id":3027,"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/pages\/429\/revisions\/3027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/media\/812"}],"wp:attachment":[{"href":"https:\/\/grosekoindarra.webclientes.es\/fr\/wp-json\/wp\/v2\/media?parent=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}